{"id":2480,"date":"2024-03-30T11:43:52","date_gmt":"2024-03-30T10:43:52","guid":{"rendered":"http:\/\/www.airoller.fr\/wordpress\/?p=2480"},"modified":"2024-04-24T08:23:06","modified_gmt":"2024-04-24T06:23:06","slug":"stage-roller-et-hockey-sur-gazon-26-avril-2024","status":"publish","type":"post","link":"https:\/\/www.airoller.fr\/wordpress\/2024\/03\/30\/stage-roller-et-hockey-sur-gazon-26-avril-2024\/","title":{"rendered":"STAGE Roller et Hockey sur Gazon &#8211; 26 Avril 2024"},"content":{"rendered":"\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2344 size-full\" src=\"https:\/\/www.airoller.fr\/wordpress\/wp-content\/uploads\/2023\/08\/panneau-roller.png\" alt=\"\" width=\"151\" height=\"182\" \/><strong><a href=\"https:\/\/www.hockey-hgs.com\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2482 size-full\" src=\"https:\/\/www.airoller.fr\/wordpress\/wp-content\/uploads\/2024\/03\/logo-hgs.webp\" alt=\"\" width=\"72\" height=\"78\" \/><\/a><\/strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1737\" src=\"https:\/\/www.airoller.fr\/wordpress\/wp-content\/uploads\/2021\/06\/air-roller-150x150.png\" alt=\"\" width=\"72\" height=\"78\" \/>AIR ROLLER s&rsquo;associe pour vous proposer un stage de roller encadr\u00e9 par notre club\u00a0et un stage de hockey sur gazon g\u00e9r\u00e9 par HOCKEY GARONNE SPORTS.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>Date<\/strong> : vendredi 26 avril<\/p>\n<p><strong>Horaires<\/strong> : 9h30 \u00e0 17h00<\/p>\n<p><strong>Tranche d&rsquo;\u00e2ge<\/strong> : 6 \u00e0 12 ans &#8211; Ouvert aux adh\u00e9rents du club et aux non adh\u00e9rents<\/p>\n<p><strong>Nombre de places<\/strong> : 12<\/p>\n<p><strong>Prix<\/strong> : 10\u20ac adh\u00e9rent \/ 15\u20ac non adh\u00e9rent<\/p>\n<p><strong>D\u00e9roul\u00e9<\/strong> :<\/p>\n<p>&#8211; Matin : Stage de roller<br \/>&#8211; Apr\u00e8s-midi : Stage de hockey sur gazon<\/p>\n<p><strong>Lieux<\/strong> : <br \/>&#8211; Gymnase Dupaty : 62 Rue Chantecrit, 33300 Bordeaux (quartier Chartrons)<br \/>&#8211; Jardin sportif Suzanne Lenglen : Rue Ren\u00e9 Buthaud, 33100 Bordeaux (quartier la Bastide)<br \/>Les enfants changeront de site via les transports en commun, ils seront encadr\u00e9s par 2 \u00e0 3 moniteurs au total. Une d\u00e9charge sera \u00e0 signer par les parents lors de l&rsquo;inscription.<br \/>Les parents d\u00e9poseront leurs enfants au Gymnase Dupaty le matin et les r\u00e9cup\u00e9reront au m\u00eame endroit.<\/p>\n<p><strong>A pr\u00e9voir<\/strong> :<br \/>&#8211; Un pique-nique et des go\u00fbters<br \/>&#8211; Ses rollers + son casque + ses protections (ou nous indiquer la pointure et taille n\u00e9cessaire au moins une semaine avant le stage)<\/p>\n<p>Inscription <a href=\"https:\/\/www.helloasso.com\/associations\/air-roller\/evenements\/stage-enfants-avril-2024\">ici via Hello Asso <\/a> ou <a href=\"https:\/\/www.airoller.fr\/wordpress\/wp-content\/uploads\/2024\/03\/2024-04-Stage-enfants-avril-Bulletin-et-QS.pdf\">via un formulaire papier<\/a> \u00e0 nous remettre par courrier a l&rsquo;adresse du local de l&rsquo;association ( AIR Roller\u00a0 16 rue Ausone 33000 Bordeaux)\u00a0<br \/><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AIR ROLLER s&rsquo;associe pour vous proposer un stage de roller encadr\u00e9 par notre club\u00a0et un stage de hockey sur gazon g\u00e9r\u00e9 par HOCKEY GARONNE SPORTS. \u00a0 \u00a0 Date : vendredi 26 avril Horaires : 9h30 \u00e0 17h00 Tranche d&rsquo;\u00e2ge : 6 \u00e0 12 ans &#8211; Ouvert aux adh\u00e9rents du club et aux non adh\u00e9rents Nombre [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,5,13],"tags":[],"class_list":["post-2480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-association","category-evenements","category-stages"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=2480"}],"version-history":[{"count":2,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2480\/revisions"}],"predecessor-version":[{"id":2484,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2480\/revisions\/2484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/media\/2344"}],"wp:attachment":[{"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=2480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.airoller.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=2480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}